{"id":2330,"date":"2015-05-18T16:00:24","date_gmt":"2015-05-18T16:00:24","guid":{"rendered":"http:\/\/www.astrologosastrologia.com.pt\/blog\/?p=2330"},"modified":"2015-05-18T16:02:37","modified_gmt":"2015-05-18T16:02:37","slug":"wicca-principios-e-crencas","status":"publish","type":"post","link":"https:\/\/www.astrologosastrologia.com.pt\/blog\/wicca\/wicca-principios-e-crencas\/","title":{"rendered":"Wicca, Principios e cren\u00e7as"},"content":{"rendered":"<p><strong><a href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/wp-content\/uploads\/2015\/05\/Portal-ae3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2214\" src=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/wp-content\/uploads\/2015\/05\/Portal-ae3.jpg\" alt=\"Portal a&amp;e\" width=\"47\" height=\"86\" \/><\/a><span style=\"color: #ff0000;\">Princ\u00edpios e cren\u00e7as wiccanianas<\/span><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Muitos consideram a <a href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/wicca\/\" data-internallinksmanager029f6b8e52c=\"12\" title=\"Wicca, veja mais aqui\">Wicca<\/a> uma religi\u00e3o Polite\u00edsta uma vez que reverenciamos v\u00e1rias <a href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/deuses\/\" data-internallinksmanager029f6b8e52c=\"10\" title=\"Deuses e Deusas, veja mais aqui\">divindades<\/a> como faces da <a href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/deuses\/\" data-internallinksmanager029f6b8e52c=\"10\" title=\"Deuses e Deusas, veja mais aqui\">Deusa<\/a> e do <a href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/deuses\/\" data-internallinksmanager029f6b8e52c=\"10\" title=\"Deuses e Deusas, veja mais aqui\">Deus<\/a>. Mesmo podendo ser considerada Polite\u00edsta, por reverenciar v\u00e1rios <a href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/deuses\/\" data-internallinksmanager029f6b8e52c=\"10\" title=\"Deuses e Deusas, veja mais aqui\">Deuses<\/a>, e at\u00e9 mesmo Monote\u00edsta, uma vez que acredita em uma \u00fanica fonte de energia (a <a href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/deuses\/\" data-internallinksmanager029f6b8e52c=\"10\" title=\"Deuses e Deusas, veja mais aqui\">Deusa<\/a>), a <a href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/wicca\/\" data-internallinksmanager029f6b8e52c=\"12\" title=\"Wicca, veja mais aqui\">Wicca<\/a> \u00e9 na realidade uma religi\u00e3o Henote\u00edsta, observando a exist\u00eancia de v\u00e1rias <a href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/deuses\/\" data-internallinksmanager029f6b8e52c=\"10\" title=\"Deuses e Deusas, veja mais aqui\">divindades<\/a>, mas atribuindo a cria\u00e7\u00e3o de todas a uma <a href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/deuses\/\" data-internallinksmanager029f6b8e52c=\"10\" title=\"Deuses e Deusas, veja mais aqui\">divindade<\/a> suprema: a <a href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/deuses\/\" data-internallinksmanager029f6b8e52c=\"10\" title=\"Deuses e Deusas, veja mais aqui\">Deusa<\/a>. \u00c9 tamb\u00e9m Pante\u00edsta em sua vis\u00e3o de mundo, o que significa o reconhecimento do Sagrado em todas as coisas, vendo <a href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/deuses\/\" data-internallinksmanager029f6b8e52c=\"10\" title=\"Deuses e Deusas, veja mais aqui\">Deuses<\/a> e a natureza como sendo unidos. Assim, o mundo torna-se divino e sagrado em sua ess\u00eancia.<\/p>\n<p>A Teoria do Efeito Borboleta, para descrever como pequenas varia\u00e7\u00f5es podem afetar um gigante e complexo sistema, \u00e9 extremamente compat\u00edvel com a vis\u00e3o de mundo e espiritualidade propostas pela <a href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/wicca\/\" data-internallinksmanager029f6b8e52c=\"12\" title=\"Wicca, veja mais aqui\">Wicca<\/a>.<\/p>\n<p>Para n\u00f3s, o Divino n\u00e3o \u00e9 algo transcendente e nem separado da humanidade. Ele est\u00e1 dentro, fora e ao nosso redor. Acreditamos que todas as coisas que existem <a href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/santos\/\" data-internallinksmanager029f6b8e52c=\"9\" title=\"Santos e Santas, veja mais aqui\">s\u00e3o<\/a> diferentes manifesta\u00e7\u00f5es da <a href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/deuses\/\" data-internallinksmanager029f6b8e52c=\"10\" title=\"Deuses e Deusas, veja mais aqui\">Deusa<\/a>, pois por Ela foram criadas. Isto desenvolve a id\u00e9ia de que tudo esta interconectado, como fios de uma mesma teia que forma o grande todo. Se um de seusfios for danificado, toda a teia tamb\u00e9m ser\u00e1. Assim, preju\u00edzos individuais <a href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/santos\/\" data-internallinksmanager029f6b8e52c=\"9\" title=\"Santos e Santas, veja mais aqui\">s\u00e3o<\/a> encarados de maneira coletiva e o dano de um \u00e9 prejudicial para o todo. A isso damos o nome de iman\u00eancia. Este conceito \u00e9 muito antigo e podemos encontrar refer\u00eancias a ele em diversas culturas centradas na Terra. Recentemente a F\u00edsica descobriu algo interessante que nomeou de \u201cEfeito Borboleta\u201d, que afirma cientificamente que tudo o que existe est\u00e1 interligado. Em termos de clima, por exemplo, isso traduz-se na no\u00e7\u00e3o deque uma borboleta que agite o ar com as suas asas hoje na Austr\u00e1lia pode influenciar tempestades no pr\u00f3ximo m\u00eas no Texas. Isto demonstra que pequenas a\u00e7\u00f5es provocam conseq\u00fc\u00eancias gigantescas e os princ\u00edpios das cren\u00e7as Wiccaniana est\u00e3o fundamentados exatamente nisto. Este \u00e9 o ponto de partida para entendimento da conduta e \u00e9tica de um <a href=\"https:\/\/www.magianegra.com.pt\/\" data-internallinksmanager029f6b8e52c=\"4\" title=\"Bruxas e Bruxos, saiba tudo aqui\" target=\"_blank\" rel=\"noopener\">Bruxo<\/a>. \u00c9tica consiste em padr\u00f5es de conduta que incluem um julgamento e uma filosofia moral. N\u00e3o existe nenhum conjunto de \u00e9ticas que podem ser aplicadas a todas as pessoas, em todos os tempos e religi\u00f5es. A \u00e9tica \u00e9 geralmente baseada em padr\u00f5es locais e sociais de onde vivemos.<\/p>\n<p>A <a href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/wicca\/\" data-internallinksmanager029f6b8e52c=\"12\" title=\"Wicca, veja mais aqui\">Wicca<\/a> n\u00e3o possui grandes listas de regras e leis para serem seguidas, mas existem certas condutas com as quais muitos Wiccanianos norteiam suas vidas. Todas elas <a href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/santos\/\" data-internallinksmanager029f6b8e52c=\"9\" title=\"Santos e Santas, veja mais aqui\">s\u00e3o<\/a> baseadas em um senso comum, os valores centrais, que \u00e9 uma forte diretriz para a \u00e9tica humana, inclusive a Wiccaniana. A <a href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/wicca\/\" data-internallinksmanager029f6b8e52c=\"12\" title=\"Wicca, veja mais aqui\">Wicca<\/a> \u00e9 uma religi\u00e3o libert\u00e1ria, onde n\u00e3o existem diversas regras que digam oque devemos fazer ou como devemos viver. Apenas dois princ\u00edpios <a href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/santos\/\" data-internallinksmanager029f6b8e52c=\"9\" title=\"Santos e Santas, veja mais aqui\">s\u00e3o<\/a> aceitos de maneira comum a todos os Wiccanianos: o Dogma da Arte, que \u00e9 tamb\u00e9m chamado de Rede Wiccaniana, e a Lei Tr\u00edplice. Aqui encontram-se listados alguns dos princ\u00edpios e cren\u00e7as Wiccanianas mais comuns.<\/p>\n<p>O DOGMA DA ARTE<\/p>\n<p>\u201cFa\u00e7a o que quiser, desde que n\u00e3o fa\u00e7a mal a nada, nem ningu\u00e9m\u201d<\/p>\n<p>Esta \u00e9 seguramente a principal diretriz Wiccaniana e \u00e9 levada em considera\u00e7\u00e3o todas as vezes que realizamos um ato m\u00e1gico e no nosso comportamento di\u00e1rio. Assim como em muitas religi\u00f5es a <a href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/wicca\/\" data-internallinksmanager029f6b8e52c=\"12\" title=\"Wicca, veja mais aqui\">Wicca<\/a> tamb\u00e9m pratica Magia. N\u00f3s <a href=\"https:\/\/www.magianegra.com.pt\/\" data-internallinksmanager029f6b8e52c=\"4\" title=\"Bruxas e Bruxos, saiba tudo aqui\" target=\"_blank\" rel=\"noopener\">Bruxos<\/a> acreditamos que a mente e o corpo humano possuem o poder de efetuar mudan\u00e7as nos acontecimentos de maneiras ainda n\u00e3o compreendidas pela ci\u00eancia. Em nossos rituais, onde honramos nossos <a href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/deuses\/\" data-internallinksmanager029f6b8e52c=\"10\" title=\"Deuses e Deusas, veja mais aqui\">Deuses<\/a>, realizamos diversos <a href=\"https:\/\/www.magianegra.com.pt\/\" data-internallinksmanager029f6b8e52c=\"5\" title=\"Bruxaria, saiba tudo aqui\" target=\"_blank\" rel=\"noopener\">feiti\u00e7os<\/a> para in\u00fameros prop\u00f3sitos como cura e supera\u00e7\u00e3o de problemas. No entanto, a Magia sempre \u00e9 praticada de acordo com um c\u00f3digo de \u00e9tica que afirma que s\u00f3 podemos ajudar outros, ou a n\u00f3s mesmos, respeitando o livre arb\u00edtrio das pessoas envolvidas e quando isso n\u00e3o prejudicar ningu\u00e9m. N\u00e3o fazer mal a nada nem NINGU\u00c9M significa n\u00e3o prejudicar a natureza, as pessoas ao nosso redor e n\u00f3s mesmos. Isso implica observar nosso modo devida, incluindo h\u00e1bitos alimentares e comportamentais e principalmente viver em harmonia com a natureza levando em considera\u00e7\u00e3o os 3rs: Reduzir, Reciclar e Reutilizar. O Dogma da Arte incentiva o respeito e a celebra\u00e7\u00e3o \u00e0 diversidade, fazendo com que cada ser honre as diferen\u00e7as existentes, repudiando todas as formas de preconceito, em vez de promulgar a intoler\u00e2ncia. Esta atitude \u00e9 a ess\u00eancia da <a href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/wicca\/\" data-internallinksmanager029f6b8e52c=\"12\" title=\"Wicca, veja mais aqui\">Wicca<\/a>.<\/p>\n<p>A LEI TR\u00cdPLICE<\/p>\n<p>\u201cTudo o que fizermos, para o bem ou mal, a n\u00f3s retornar\u00e1 triplicadamente e nesta encarna\u00e7\u00e3o\u201d.<\/p>\n<p>Esta \u00e9 a Lei Tr\u00edplice que est\u00e1 fundamenta no poder da iman\u00eancia. Se desejarmos o bem colheremos o bem, se fizermos o mal ele tamb\u00e9m retornar\u00e1 invariavelmente. Acreditamos que as energias que criamos influenciam o que acontece conosco. Ela \u00e9 perfeitamente compat\u00edvel com a lei de causa e efeito, a\u00e7\u00e3o e rea\u00e7\u00e3o. H\u00e1 at\u00e9 quem diga que Gardner retirou esse conceito das religi\u00f5es orientais para inclu\u00ed-lo na <a href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/wicca\/\" data-internallinksmanager029f6b8e52c=\"12\" title=\"Wicca, veja mais aqui\">Wicca<\/a>. A Lei Tr\u00edplice est\u00e1 centrada na Lei da iman\u00eancia e \u00e9 facilmente explicada pela teoria da teia da vida e do efeito borboleta. Ela \u00e9 tr\u00edplice porque todas as a\u00e7\u00f5es, m\u00e1gicas ou n\u00e3o, causam efeito na vida de quem pr\u00e1tica o ato, sofre as a\u00e7\u00f5es desse ato, e indiretamente na vida daqueles que est\u00e3o ligados da v\u00edtima dessa a\u00e7\u00e3o e no mundo ao nosso redor. \u00c9 l\u00f3gico e natural que estas a\u00e7\u00f5es voltem ao seu emissor em grau intensificado. isso pode ser facilmente explicada atrav\u00e9s de uma alegoria f\u00edsica e simples: &#8221;<\/p>\n<p>Se voc\u00ea plantar pimentas, n\u00e3o colher\u00e1 morangos. Colher\u00e1 pimenta numa quantidade muito maior do que plantou. Plante apenas uma semente de pimenta e ter\u00e1 uma pimenteira inteira&#8221;.<\/p>\n<p>Esta lei divina n\u00e3o tem nada de cruel e nem \u00e9 fruto de uma <a href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/deuses\/\" data-internallinksmanager029f6b8e52c=\"10\" title=\"Deuses e Deusas, veja mais aqui\">Deusa<\/a> ou <a href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/deuses\/\" data-internallinksmanager029f6b8e52c=\"10\" title=\"Deuses e Deusas, veja mais aqui\">Deus<\/a> injustos. Ela \u00e9 fruto de nossas pr\u00f3prias a\u00e7\u00f5es e \u00e9 provocada por n\u00f3s mesmos en\u00e3o por uma <a href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/deuses\/\" data-internallinksmanager029f6b8e52c=\"10\" title=\"Deuses e Deusas, veja mais aqui\">Divindade<\/a> que ir\u00e1 nos punir em fun\u00e7\u00e3o de nossos feitos. Quem est\u00e1 nos punindo somos n\u00f3s mesmos ao transgredir a regra mais importante da vida: o respeito ao livre arb\u00edtrio alheio. Isso n\u00e3o significa que fazer o mal \u00e9 pecado ou coisa do g\u00eanero. O conceito de pecado n\u00e3o existe na <a href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/wicca\/\" data-internallinksmanager029f6b8e52c=\"12\" title=\"Wicca, veja mais aqui\">Wicca<\/a>. A Lei tr\u00edplice \u00e9 chamada de lei pois \u00e9 como uma lei que ela opera. Todos n\u00f3s somos livres e podemos transgredir qualquer lei, mas sofreremos invariavelmente as consequ\u00eancias de nossos atos. <a href=\"https:\/\/www.magianegra.com.pt\/\" data-internallinksmanager029f6b8e52c=\"4\" title=\"Bruxas e Bruxos, saiba tudo aqui\" target=\"_blank\" rel=\"noopener\">Bruxos<\/a> <a href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/santos\/\" data-internallinksmanager029f6b8e52c=\"9\" title=\"Santos e Santas, veja mais aqui\">s\u00e3o<\/a> pessoas s\u00e1bias e sabem que aquilo que desejam representa a energia que vibram. Assim, se esfor\u00e7am ao m\u00e1ximo para vibrarem num n\u00edvel de energia positiva, canalizada para o bem de tudo e de todos. Se todos desejassem aos outros exatamente o que desejariam a si mesmos, em breve o mundo estaria repleto de b\u00ean\u00e7\u00e3os e positividade. A Lei Tr\u00edplice nos lembra que prejudicar outros traz preju\u00edzo para n\u00f3s mesmos. Vivemos num mundo onde compartilhamos a mesma energia. Se por um lado a Lei Tr\u00edplice pode trabalhar contra voc\u00ea, ela tamb\u00e9m pode trabalhar ao seu favor dependendo de seu comportamento, pensamentos e a\u00e7\u00f5es. Fa\u00e7a sua parte!<\/p>\n<p>(Fonte: <a href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/wicca\/\" data-internallinksmanager029f6b8e52c=\"12\" title=\"Wicca, veja mais aqui\">Wicca<\/a> para todos, de Claudiney Prieto)<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/wp-content\/uploads\/2015\/05\/Portal-ae.jpg\" alt=\"Portal a&amp;e\" \/>\u00a0<strong>Voltar ao tema:<\/strong><\/p>\n<p><span style=\"color: #008000;\">|\u00a0<a style=\"color: #008000;\" href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/simpatias\/simpatias-amor\/\">Simpatias Amor<\/a>\u00a0|\u00a0<a style=\"color: #008000;\" href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/amarracoes-2\/\" target=\"_blank\">Amarra\u00e7\u00f5es<\/a>\u00a0|\u00a0<a style=\"color: #008000;\" href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/esoterismo\/encantamentos\/\">Encantamentos<\/a>\u00a0|\u00a0<a style=\"color: #008000;\" href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/simpatias\/simpatias-ciganas\/\">Simpatias ciganas<\/a>\u00a0|\u00a0<strong><a style=\"color: #008000;\" href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/wicca\/\">Wicca<\/a>\u00a0<\/strong>|<\/span><\/p>\n<p><span style=\"color: #008000;\">|\u00a0<a style=\"color: #008000;\" href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/simpatias\/simpatias-magias-egipcias\/\">Simpatias &amp; magias eg\u00edpcias<\/a> | <a style=\"color: #008000;\" href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/banhos-magicos\/\">Banhos m\u00e1gicos<\/a> | <a style=\"color: #008000;\" href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/esoterismo\/talismas-amuletos-patuas\/\" target=\"_blank\">Amuletos &amp; Talism\u00e3s<\/a> |<\/span><\/p>\n<p><span style=\"color: #008000;\">|\u00a0<a style=\"color: #008000;\" href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/simpatias\/simpatias-dinheiro-prosperidade\/\">Simpatias Dinheiro &amp; Prosperidade<\/a> | <a style=\"color: #008000;\" href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/esoterismo\/incensos\/\">Incensos m\u00e1gicos<\/a> |\u00a0<a style=\"color: #008000;\" href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/simpatias\/simpatias-angelicais\/\" target=\"_blank\">Simpatias angelicais<\/a>\u00a0|<\/span><\/p>\n<p><span style=\"color: #008000;\">|\u00a0<a style=\"color: #008000;\" href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/simpatias\/simpatias-para-engravidar\/\">Simpatias para engravidar<\/a>\u00a0|\u00a0<\/span><\/p>\n ","protected":false},"excerpt":{"rendered":"<p>Princ\u00edpios e cren\u00e7as wiccanianas &nbsp; Muitos consideram a Wicca uma religi\u00e3o Polite\u00edsta uma vez que reverenciamos v\u00e1rias divindades como faces da Deusa e do Deus. Mesmo podendo ser considerada Polite\u00edsta, por reverenciar v\u00e1rios Deuses, e at\u00e9 mesmo Monote\u00edsta, uma vez que acredita em uma \u00fanica fonte de energia (a Deusa), a Wicca \u00e9 na realidade uma religi\u00e3o Henote\u00edsta, observando a<\/p>\n","protected":false},"author":1,"featured_media":2332,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[144],"tags":[352,74,615,372,351,75],"class_list":["post-2330","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wicca","tag-feiticos-wicca","tag-magia-wicca","tag-principios-e-crencas","tag-religiao-wicca","tag-rituais-wicca","tag-wicca"],"_links":{"self":[{"href":"https:\/\/www.astrologosastrologia.com.pt\/blog\/wp-json\/wp\/v2\/posts\/2330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.astrologosastrologia.com.pt\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.astrologosastrologia.com.pt\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.astrologosastrologia.com.pt\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.astrologosastrologia.com.pt\/blog\/wp-json\/wp\/v2\/comments?post=2330"}],"version-history":[{"count":3,"href":"https:\/\/www.astrologosastrologia.com.pt\/blog\/wp-json\/wp\/v2\/posts\/2330\/revisions"}],"predecessor-version":[{"id":2334,"href":"https:\/\/www.astrologosastrologia.com.pt\/blog\/wp-json\/wp\/v2\/posts\/2330\/revisions\/2334"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.astrologosastrologia.com.pt\/blog\/wp-json\/wp\/v2\/media\/2332"}],"wp:attachment":[{"href":"https:\/\/www.astrologosastrologia.com.pt\/blog\/wp-json\/wp\/v2\/media?parent=2330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.astrologosastrologia.com.pt\/blog\/wp-json\/wp\/v2\/categories?post=2330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.astrologosastrologia.com.pt\/blog\/wp-json\/wp\/v2\/tags?post=2330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}