{"id":3250,"date":"2015-05-27T07:54:39","date_gmt":"2015-05-27T07:54:39","guid":{"rendered":"http:\/\/www.astrologosastrologia.com.pt\/blog\/?p=3250"},"modified":"2015-05-27T07:54:39","modified_gmt":"2015-05-27T07:54:39","slug":"ervas-magicas-ervas-para-encantamentos-e-rituais","status":"publish","type":"post","link":"https:\/\/www.astrologosastrologia.com.pt\/blog\/ervas\/ervas-magicas-ervas-para-encantamentos-e-rituais\/","title":{"rendered":"Ervas m\u00e1gicas &#8211; Ervas para encantamentos e rituais"},"content":{"rendered":"<p style=\"text-align: justify;\"><img decoding=\"async\" src=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/wp-content\/uploads\/2015\/05\/Portal-ae.jpg\" alt=\"Portal a&amp;e\" \/><span style=\"color: #ff0000;\"><strong>Ervas m\u00e1gicas &#8211; Ervas para encantamentos e rituais<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Um dos pontos mais explorados no reino da magia das plantas \u00e9 o seu uso como elemento facilitador em determinadas situa\u00e7\u00f5es de nossas vidas. Esse uso \u00e9 feito por meio de encantamentos e rituais que empregam, al\u00e9m das plantas, os minerais e os elementos animais, muitas vezes misturados em complexas f\u00f3rmulas m\u00e1gicas. Esses conhecimentos nos foram legados pelos herboristas, alquimistas, bot\u00e2nicos e sacerdotes do passado. Seus conhecimentos por vezes se perderam, restando apenas informa\u00e7\u00f5es dispersas e pouco consistentes curiosidade na maioria das pessoas.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">ALGUNS USOS ENCANTAT\u00d3RIOS DAS PLANTAS<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Como afrodis\u00edaco: \u00a0cravo-da\u00edndia, baunilha, canela, cam\u00e9lia, cardamomo, coentro, lev\u00edstico, pimenta-da-jamaica, pimentas c\u00e1psico, laranja-azeda, flor de datura, abr\u00f3tano, jasmim, ilangue -ilangue, pimenta-do-reino, patchouli, s\u00e1lvia esclar\u00e9ia, s\u00e2ndalo, rosa.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Para ajudar na medita\u00e7\u00e3o: \u00eanula, zimbro, b\u00e1lsamo-de-tolu, ciper\u00e1cea, s\u00e1lvia esclar\u00e9ia, giesta, glic\u00ednia, s\u00e2ndalo, c\u00e1lamo-arom\u00e1tico, magn\u00f3lia, mirra.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Para atrair sorte: canela, jasmim, l\u00f3tus, jacinto, baunilha, cumaru, ger\u00e2nio, noz-moscada, bergamota, cipreste.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Para atrair sucesso e promo\u00e7\u00e3o na carreira:\u00a0 azal\u00e9ia, cravo-de-defunto, ol\u00edbano, hortel\u00e3-pimenta, erva-cidreira, hissopo.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Para atrair um amor: ervilha-de-cheiro, l\u00f3tus, jacinto, baunilha, b\u00e9tula, cam\u00e9lia, coentro, l\u00edrioflorentino, rosa, cumarina, laranja-azeda.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Para estimular a clarivid\u00eancia:\u00a0 a\u00e7afr\u00e3o, capim-lim\u00e3o, louro, anis-estrelado.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Para estimular a mente: Babosa, aipo, c\u00e2nfora, \u00eanula, zimbro, anis-estrelado, estoraque, funcho, madressilva, cacto, c\u00e1lamo-arom\u00e1tico, gengibre.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Para estimular <a href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/sonhos\/\" data-internallinksmanager029f6b8e52c=\"18\" title=\"Sonhos, saiba mais aqui\">sonhos<\/a> prof\u00e9ticos:\u00a0 pe\u00f4nia, mimosa, amar\u00edlis, giesta.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Para limpar os ambientes de energia negativa:\u00a0 c\u00e2nfora, comigo-ningu\u00e9m-pode, guin\u00e9, arruda, alecrim, espada-de-<a href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/santos\/\" data-internallinksmanager029f6b8e52c=\"9\" title=\"Santos e Santas, veja mais aqui\">s\u00e3o<\/a>-jorge.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Para melhorar as finan\u00e7as: camomila, ol\u00edbano, alfazema, erva-cidreira, cedro, hissopo, cipreste, ab\u00f3bora.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Para promover amizades:\u00a0 ervilha-de-cheiro, urze, citronela, erva-cidreira, cumarina.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Para proteger contra <a href=\"https:\/\/www.magianegra.com.pt\/\" data-internallinksmanager029f6b8e52c=\"3\" title=\"Magia Negra, saiba tudo aqui\" target=\"_blank\" rel=\"noopener\">magia negra<\/a> e negatividade:\u00a0 alecrim, louro, jasmim, cenoura, violeta, hortel\u00e3-pimenta, verbena, assa-f\u00e9tida, ger\u00e2nio, manjeric\u00e3o, patchouli, hissopo, noz-moscada, bergamota.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Para purificar os altares e untar equipamentos ritual\u00edsticos:\u00a0 falsa-ac\u00e1cia, flor de maracuj\u00e1, jacinto, benjoim, rosa, s\u00e1lvia, mirra.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Para trazer paz e harmonia \u00e0s rela\u00e7\u00f5es:\u00a0 gard\u00eania, alfazema, narciso, urze, violeta, hissopo.<\/p>\n<p style=\"text-align: justify;\">\n<p><img decoding=\"async\" src=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/wp-content\/uploads\/2015\/05\/Portal-ae.jpg\" alt=\"Portal a&amp;e\" \/>\u00a0<strong>Voltar ao tema: <span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/esoterismo\/ervas-magicas\/\" target=\"_blank\">Ervas m\u00e1gicas<\/a>\u00a0<\/span>| <\/strong><span style=\"color: #008000;\"><a style=\"color: #008000;\" href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/horoscopos\/\">Hor\u00f3scopos<\/a> <strong>|<\/strong><\/span><\/p>\n<p><span style=\"color: #008000;\">|\u00a0<a style=\"color: #008000;\" href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/simpatias\/simpatias-amor\/\">Simpatias Amor<\/a>\u00a0|\u00a0<a style=\"color: #008000;\" href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/amarracoes-2\/\" target=\"_blank\">Amarra\u00e7\u00f5es<\/a>\u00a0|\u00a0<a style=\"color: #008000;\" href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/esoterismo\/encantamentos\/\">Encantamentos<\/a>\u00a0|\u00a0<a style=\"color: #008000;\" href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/simpatias\/simpatias-ciganas\/\">Simpatias ciganas<\/a>\u00a0|\u00a0<a style=\"color: #008000;\" href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/wicca\/\">Wicca<\/a>\u00a0|<\/span><\/p>\n<p><span style=\"color: #008000;\">|\u00a0<a style=\"color: #008000;\" href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/simpatias\/simpatias-magias-egipcias\/\">Simpatias &amp; magias eg\u00edpcias<\/a> | <a style=\"color: #008000;\" href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/banhos-magicos\/\">Banhos m\u00e1gicos<\/a> | <a style=\"color: #008000;\" href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/esoterismo\/talismas-amuletos-patuas\/\" target=\"_blank\">Amuletos &amp; Talism\u00e3s<\/a> |<\/span><\/p>\n<p><span style=\"color: #008000;\">|\u00a0<a style=\"color: #008000;\" href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/simpatias\/simpatias-dinheiro-prosperidade\/\">Simpatias Dinheiro &amp; Prosperidade<\/a> | <a style=\"color: #008000;\" href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/esoterismo\/incensos\/\">Incensos m\u00e1gicos<\/a> |\u00a0<a style=\"color: #008000;\" href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/simpatias\/simpatias-angelicais\/\" target=\"_blank\">Simpatias angelicais<\/a>\u00a0|<\/span><\/p>\n<p><span style=\"color: #008000;\">|\u00a0<a style=\"color: #008000;\" href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/simpatias\/simpatias-para-engravidar\/\">Simpatias para engravidar<\/a>\u00a0| <a style=\"color: #008000;\" href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/feng-shui\/\">Feng Shui<\/a> | <a style=\"color: #008000;\" href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/simpatias\/simpatias-lar\/\" target=\"_blank\">Simpatias para o Lar<\/a> |<\/span><\/p>\n<p><span style=\"color: #008000;\">| <a style=\"color: #008000;\" href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/simpatias\/simpatias-magias-e-feiticos-rapidos\/\" target=\"_blank\">Simpatias, magias &amp; feiti\u00e7os r\u00e1pidos<\/a> | <a style=\"color: #008000;\" href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/magia\/magia-magia-das-fadas\/\" target=\"_blank\">Magia das Fadas<\/a> | <a style=\"color: #008000;\" href=\"http:\/\/www.astrologosastrologia.com.pt\/blog\/magia\/magia-pocoes-magicas\/\">Po\u00e7\u00f5es m\u00e1gicas<\/a> |<\/span><\/p>\n ","protected":false},"excerpt":{"rendered":"<p>Ervas m\u00e1gicas &#8211; Ervas para encantamentos e rituais Um dos pontos mais explorados no reino da magia das plantas \u00e9 o seu uso como elemento facilitador em determinadas situa\u00e7\u00f5es de nossas vidas. Esse uso \u00e9 feito por meio de encantamentos e rituais que empregam, al\u00e9m das plantas, os minerais e os elementos animais, muitas vezes misturados em complexas f\u00f3rmulas m\u00e1gicas.<\/p>\n","protected":false},"author":1,"featured_media":3251,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[859],"tags":[864,861,865,27,872],"class_list":["post-3250","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ervas","tag-a-magia-das-ervas","tag-ervas","tag-ervas-e-plantas","tag-ervas-magicas","tag-ervas-magicas-ervas-para-encantamentos-e-rituais"],"_links":{"self":[{"href":"https:\/\/www.astrologosastrologia.com.pt\/blog\/wp-json\/wp\/v2\/posts\/3250","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.astrologosastrologia.com.pt\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.astrologosastrologia.com.pt\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.astrologosastrologia.com.pt\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.astrologosastrologia.com.pt\/blog\/wp-json\/wp\/v2\/comments?post=3250"}],"version-history":[{"count":1,"href":"https:\/\/www.astrologosastrologia.com.pt\/blog\/wp-json\/wp\/v2\/posts\/3250\/revisions"}],"predecessor-version":[{"id":3252,"href":"https:\/\/www.astrologosastrologia.com.pt\/blog\/wp-json\/wp\/v2\/posts\/3250\/revisions\/3252"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.astrologosastrologia.com.pt\/blog\/wp-json\/wp\/v2\/media\/3251"}],"wp:attachment":[{"href":"https:\/\/www.astrologosastrologia.com.pt\/blog\/wp-json\/wp\/v2\/media?parent=3250"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.astrologosastrologia.com.pt\/blog\/wp-json\/wp\/v2\/categories?post=3250"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.astrologosastrologia.com.pt\/blog\/wp-json\/wp\/v2\/tags?post=3250"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}