{"id":2884,"count":1,"description":"","link":"https:\/\/www.astrologosastrologia.com.pt\/blog\/tag\/receita-de-peru-com-recheio-de-maca\/","name":"Receita de Peru com recheio de ma\u00e7\u00e3","slug":"receita-de-peru-com-recheio-de-maca","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.astrologosastrologia.com.pt\/blog\/wp-json\/wp\/v2\/tags\/2884","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.astrologosastrologia.com.pt\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.astrologosastrologia.com.pt\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.astrologosastrologia.com.pt\/blog\/wp-json\/wp\/v2\/posts?tags=2884"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}