{"id":3913,"count":2,"description":"","link":"https:\/\/www.astrologosastrologia.com.pt\/blog\/tag\/acorda-de-codornizes-com-marisco\/","name":"A\u00e7orda de codornizes com marisco","slug":"acorda-de-codornizes-com-marisco","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.astrologosastrologia.com.pt\/blog\/wp-json\/wp\/v2\/tags\/3913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.astrologosastrologia.com.pt\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.astrologosastrologia.com.pt\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.astrologosastrologia.com.pt\/blog\/wp-json\/wp\/v2\/posts?tags=3913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}